{"id":11464,"date":"2023-07-31T08:43:49","date_gmt":"2023-07-31T06:43:49","guid":{"rendered":"https:\/\/www.storespergolas.com\/blog\/?p=11464"},"modified":"2023-07-31T08:43:59","modified_gmt":"2023-07-31T06:43:59","slug":"toile-de-store-banne-citel-docril-00184-butterscotch","status":"publish","type":"post","link":"https:\/\/www.storespergolas.com\/blog\/toile-de-store-banne-citel-docril-00184-butterscotch\/","title":{"rendered":"Toile de store banne CITEL Docril &#8211; 00184 Butterscotch"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Pr\u00e9sentation<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La toile de store banne CITEL Docril Butterscotch 00184 est un produit de haute qualit\u00e9, 100% acrylique teint en masse, sp\u00e9cialement con\u00e7u pour les stores, parasols et pergolas. Cette toile a \u00e9t\u00e9 cr\u00e9\u00e9e pour r\u00e9pondre \u00e0 toutes les exigences du march\u00e9 de la protection solaire, notamment celles qui prot\u00e8gent contre les intemp\u00e9ries, comme la solidit\u00e9 de la couleur, la r\u00e9pulsivit\u00e9 \u00e0 l&rsquo;eau, la protection UV, la respirabilit\u00e9 et la stabilit\u00e9 dimensionnelle.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nos toiles ont une haute r\u00e9pulsivit\u00e9 \u00e0 l&rsquo;eau, bloquent jusqu&rsquo;\u00e0 90% des rayons UV, ont une grande durabilit\u00e9 et r\u00e9sistance \u00e0 l&rsquo;abrasion, ainsi qu&rsquo;une grande stabilit\u00e9 dimensionnelle et une protection inh\u00e9rente contre la pourriture et la moisissure.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La toile CITEL Docril Butterscotch est la solution optimale dans toutes les situations o\u00f9 une protection solaire et thermique est n\u00e9cessaire.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Caract\u00e9ristiques techniques<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mati\u00e8re : 100% acrylique teint en masse<\/li>\n\n\n\n<li>Longueur de la pi\u00e8ce : 60m<\/li>\n\n\n\n<li>R\u00e9f\u00e9rence : 00184<\/li>\n\n\n\n<li>Nom du dessin : Textured<\/li>\n\n\n\n<li>Nom de la toile : Butterscotch<\/li>\n\n\n\n<li>Poids : 295 g\/m\u00b2<\/li>\n\n\n\n<li>Largeur disponible en com (laize) : 120 cm<\/li>\n\n\n\n<li>R\u00e9sistance aux intemp\u00e9ries : 7-8<\/li>\n\n\n\n<li>R\u00e9sistance \u00e0 la lumi\u00e8re : 7-8<\/li>\n\n\n\n<li>Protection des UV : max. 80<\/li>\n\n\n\n<li>Transmission solaire TS : 15,96<\/li>\n\n\n\n<li>R\u00e9flexion solaire RS : 42,68<\/li>\n\n\n\n<li>Absorption solaire AS : 41,36<\/li>\n\n\n\n<li>Transmission visuelle TV : 2,88<\/li>\n\n\n\n<li>Gtot : 0,13<\/li>\n\n\n\n<li>Confort visuel : 0,03<\/li>\n\n\n\n<li>Confort thermique : 0,13<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Entretien<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Pour l&rsquo;entretien de votre toile CITEL Docril Butterscotch, nous recommandons de nettoyer le tissu avec une brosse \u00e0 poils doux et de le rincer \u00e0 l&rsquo;eau. Pour les taches localis\u00e9es, nettoyez avec un d\u00e9tergent neutre m\u00e9lang\u00e9 \u00e0 de l&rsquo;eau ti\u00e8de (maximum 38 \u00baC\/100 \u00baF) et rincez \u00e0 l&rsquo;eau. Lorsqu&rsquo;elle est utilis\u00e9e dans des stores, il est tr\u00e8s important de laisser le tissu s\u00e9cher compl\u00e8tement avant de le rouler.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Garantie<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Notre engagement envers la qualit\u00e9 et la r\u00e9sistance de nos tissus est total. Toute d\u00e9t\u00e9rioration anormale des propri\u00e9t\u00e9s physiques et de la couleur des tissus Docril est couverte, \u00e0 condition que les conseils d&rsquo;entretien aient \u00e9t\u00e9 correctement suivis. Notre garantie s&rsquo;\u00e9tend sur 10 ans.<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;article est d\u00e9di\u00e9 \u00e0 la toile de store banne CITEL Docril &#8211; 00184 Butterscotch, un produit de haute qualit\u00e9, 100% acrylique teint en masse, avec des caract\u00e9ristiques exceptionnelles. La toile a une grande durabilit\u00e9, une r\u00e9sistance \u00e0 l&rsquo;abrasion, une stabilit\u00e9 dimensionnelle et une protection contre la pourriture et la moisissure. Les caract\u00e9ristiques techniques du produit et des conseils pour son entretien sont \u00e9galement fournis. Le fabricant offre une garantie de 10 ans sur le produit.<\/p>\n","protected":false},"author":2,"featured_media":11465,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[41,46],"class_list":["post-11464","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-toiles-de-stores","tag-toile-de-store","tag-toile-store-banne","infinite-scroll-item","masonry-post","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-25","no-featured-image-padding"],"_links":{"self":[{"href":"https:\/\/www.storespergolas.com\/blog\/wp-json\/wp\/v2\/posts\/11464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.storespergolas.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.storespergolas.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.storespergolas.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.storespergolas.com\/blog\/wp-json\/wp\/v2\/comments?post=11464"}],"version-history":[{"count":1,"href":"https:\/\/www.storespergolas.com\/blog\/wp-json\/wp\/v2\/posts\/11464\/revisions"}],"predecessor-version":[{"id":11466,"href":"https:\/\/www.storespergolas.com\/blog\/wp-json\/wp\/v2\/posts\/11464\/revisions\/11466"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.storespergolas.com\/blog\/wp-json\/wp\/v2\/media\/11465"}],"wp:attachment":[{"href":"https:\/\/www.storespergolas.com\/blog\/wp-json\/wp\/v2\/media?parent=11464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.storespergolas.com\/blog\/wp-json\/wp\/v2\/categories?post=11464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.storespergolas.com\/blog\/wp-json\/wp\/v2\/tags?post=11464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}