{"id":11332,"date":"2023-07-24T04:58:19","date_gmt":"2023-07-24T02:58:19","guid":{"rendered":"https:\/\/www.storespergolas.com\/blog\/?p=11332"},"modified":"2023-07-24T04:58:27","modified_gmt":"2023-07-24T02:58:27","slug":"toile-de-store-banne-citel-docril-00583-serenity-blue","status":"publish","type":"post","link":"https:\/\/www.storespergolas.com\/blog\/toile-de-store-banne-citel-docril-00583-serenity-blue\/","title":{"rendered":"Toile de store banne CITEL Docril &#8211; 00583 Serenity Blue"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Pr\u00e9sentation de la toile de store banne CITEL Docril &#8211; 00583 Serenity Blue<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les toiles 100% acryliques teint\u00e9es dans la masse sont devenues un standard dans le domaine de la gestion et de la protection solaire. C&rsquo;est dans cette cat\u00e9gorie que se situe la toile de store banne CITEL Docril &#8211; 00583 Serenity Blue. Con\u00e7ue pour r\u00e9pondre aux exigences du march\u00e9, elle offre une solide protection contre les intemp\u00e9ries, une excellente solidit\u00e9 de couleur, une protection UV maximale, une bonne transpirabilit\u00e9 et une grande stabilit\u00e9 dimensionnelle.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nos toiles CITEL Docril ont une haute r\u00e9pulsion \u00e0 l&rsquo;eau, bloquent jusqu&rsquo;\u00e0 90% des rayons UV, sont extr\u00eamement durables et r\u00e9sistantes \u00e0 l&rsquo;abrasion, offrent une grande stabilit\u00e9 dimensionnelle et une protection inh\u00e9rente contre la pourriture et la moisissure.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Caract\u00e9ristiques techniques de la toile de store banne CITEL Docril &#8211; 00583 Serenity Blue<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Mati\u00e8re<\/strong> : 100% acr\u00edlico tintado en masa (100% acrylique teint\u00e9 en masse)<\/li>\n\n\n\n<li><strong>Longueur de la pi\u00e8ce<\/strong> : 60m<\/li>\n\n\n\n<li><strong>R\u00e9f\u00e9rence<\/strong> : 00583<\/li>\n\n\n\n<li><strong>Nom du dessin<\/strong> : Solid<\/li>\n\n\n\n<li><strong>Nom de la toile<\/strong> : Serenity Blue<\/li>\n\n\n\n<li><strong>Poids<\/strong> : 295 g\/m\u00b2<\/li>\n\n\n\n<li><strong>Largeur disponible en cm (laize)<\/strong> : 120<\/li>\n\n\n\n<li><strong>R\u00e9sistance aux intemp\u00e9ries<\/strong> : 7-8<\/li>\n\n\n\n<li><strong>R\u00e9sistance \u00e0 la lumi\u00e8re<\/strong> : 7-8<\/li>\n\n\n\n<li><strong>Protection des UV<\/strong> : max. 80<\/li>\n\n\n\n<li><strong>Transmission solaire TS<\/strong> : 12,98<\/li>\n\n\n\n<li><strong>R\u00e9flexion solaire RS<\/strong> : 43,08<\/li>\n\n\n\n<li><strong>Absorption solaire AS<\/strong> : 43,94<\/li>\n\n\n\n<li><strong>Transmission visuelle TV<\/strong> : 6,17<\/li>\n\n\n\n<li><strong>Gtot<\/strong> : 0,11<\/li>\n\n\n\n<li><strong>Confort visuel (Optical value)<\/strong> : 0,06<\/li>\n\n\n\n<li><strong>Confort thermique (Thermal value)<\/strong> : 0,11<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Ces caract\u00e9ristiques techniques garantissent un confort visuel et thermique optimal, tout en prot\u00e9geant efficacement contre les intemp\u00e9ries et les rayons UV. De plus, avec une longueur de 60 m\u00e8tres et une largeur de 120 cm, la toile de store banne CITEL Docril &#8211; 00583 Serenity Blue est adapt\u00e9e pour une grande vari\u00e9t\u00e9 d&rsquo;applications.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Garantie de la toile de store banne CITEL Docril &#8211; 00583 Serenity Blue<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Garantie de 10 ans<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous nous engageons pleinement dans la qualit\u00e9 et la r\u00e9sistance de nos toiles. Toute d\u00e9t\u00e9rioration anormale des propri\u00e9t\u00e9s physiques et de la couleur des toiles CITEL Docril est couverte, \u00e0 condition que les conseils d&rsquo;entretien aient \u00e9t\u00e9 correctement suivis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En somme, la toile de store banne CITEL Docril &#8211; 00583 Serenity Blue est un choix s\u00fbr pour ceux qui cherchent une solution de protection solaire efficace, durable et esth\u00e9tique.<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Cet article pr\u00e9sente la toile de store banne CITEL Docril &#8211; 00583 Serenity Blue, une toile 100% acrylique teint\u00e9e en masse con\u00e7ue pour la protection solaire. Il d\u00e9taille ses caract\u00e9ristiques techniques et mentionne sa garantie de 10 ans.<\/p>\n","protected":false},"author":2,"featured_media":11333,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[41,46],"class_list":["post-11332","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-toiles-de-stores","tag-toile-de-store","tag-toile-store-banne","infinite-scroll-item","masonry-post","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-25","no-featured-image-padding"],"_links":{"self":[{"href":"https:\/\/www.storespergolas.com\/blog\/wp-json\/wp\/v2\/posts\/11332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.storespergolas.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.storespergolas.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.storespergolas.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.storespergolas.com\/blog\/wp-json\/wp\/v2\/comments?post=11332"}],"version-history":[{"count":1,"href":"https:\/\/www.storespergolas.com\/blog\/wp-json\/wp\/v2\/posts\/11332\/revisions"}],"predecessor-version":[{"id":11334,"href":"https:\/\/www.storespergolas.com\/blog\/wp-json\/wp\/v2\/posts\/11332\/revisions\/11334"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.storespergolas.com\/blog\/wp-json\/wp\/v2\/media\/11333"}],"wp:attachment":[{"href":"https:\/\/www.storespergolas.com\/blog\/wp-json\/wp\/v2\/media?parent=11332"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.storespergolas.com\/blog\/wp-json\/wp\/v2\/categories?post=11332"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.storespergolas.com\/blog\/wp-json\/wp\/v2\/tags?post=11332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}